{"id":5662,"date":"2021-09-08T11:37:21","date_gmt":"2021-09-08T10:37:21","guid":{"rendered":"https:\/\/leathergoods.es\/agenda-ring-binder-day-page\/"},"modified":"2023-01-07T11:57:45","modified_gmt":"2023-01-07T10:57:45","slug":"agenda-ring-binder-day-page","status":"publish","type":"page","link":"https:\/\/leathergoods.es\/en\/agenda-ring-binder-day-page\/","title":{"rendered":"Agenda Ring Binder Day page"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;50&#8243; bottom_padding=&#8221;15&#8243; overlay_strength=&#8221;0.3&#8243;][vc_column centered_text=&#8221;true&#8221; column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h6 style=\"text-align: center;\"><span style=\"color: #b7a964;\"><a style=\"color: #b7a964;\" href=\"https:\/\/leathergoods.es\/agendas-2023\/\">&lt;&lt; Return to &#8216;Agendas 2023&#8217;<\/a><\/span><\/h6>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; bg_color=&#8221;#074173&#8243; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;50&#8243; bottom_padding=&#8221;50&#8243; overlay_strength=&#8221;0.3&#8243;][vc_column centered_text=&#8221;true&#8221; column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Agenda Ring Binder Day page&#8221; font_container=&#8221;tag:h1|text_align:center|color:%23ffffff&#8221; use_theme_fonts=&#8221;yes&#8221;]<div class=\"divider-wrap\"><div style=\"height: 20px;\" class=\"divider\"><\/div><\/div>[vc_column_text]\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">Ring binder agenda. One of our most luxurious and exclusive models. It has the option of making the cases in leather or imitation leather. Different options for closure, by tab with loop, magnetized button or clasp. <\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">In addition, as in the rest of our agenda models, the covers are handmade in our facilities in Cadiz, under high standards of quality and craftsmanship.<\/span><\/p>\n[\/vc_column_text]<div class=\"divider-wrap\"><div style=\"height: 40px;\" class=\"divider\"><\/div><\/div>[nectar_btn size=&#8221;small&#8221; button_style=&#8221;regular-tilt&#8221; button_color=&#8221;Accent-Color&#8221; color_override=&#8221;#b7a964&#8243; icon_family=&#8221;none&#8221; url=&#8221;#formulario&#8221; text=&#8221;REQUEST A BUDGET&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;40&#8243; bottom_padding=&#8221;40&#8243; overlay_strength=&#8221;0.3&#8243;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; width=&#8221;1\/2&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h2 style=\"text-align: left;\"><span style=\"color: #074173;\">Features<\/span><\/h2>\n[\/vc_column_text]<div class=\"divider-wrap\"><div style=\"height: 20px;\" class=\"divider\"><\/div><\/div>[vc_column_text]\n<ul>\n<li><strong>Agenda ring binder day page<\/strong> (six pages per week)<\/li>\n<li>352 pages + 16 pages of full color cartography.<\/li>\n<li>Main language, Spanish. Additional: days of the week and months in English, French, German and Portuguese.<\/li>\n<li>Ecological offset paper, natural color, 90 grams.<\/li>\n<li>Offset printing in two inks, blue and gray.<\/li>\n<li>Binding with ring mechanisms. 4 holes for model DA-17 and 6 holes for model DA-15.<\/li>\n<li>Special cases handmade in Spain by expert leather workers. Cushioned cardboard and stitched edges. Several departments for documents.<\/li>\n<li>Materials: a wide range of options in leather, eco-leather, vegan materials and others.<\/li>\n<li>Recording tape or satin reading point.<\/li>\n<li>Calendars, yearly planner, useful telephone numbers, note pages&#8230;<\/li>\n<li>Presentation: luxury box lined in black.<\/li>\n<li><strong>Available sizes: 15 x 21 cm (model DA-15) \/ 17 x 24 cm (model DA-17)<\/strong><\/li>\n<\/ul>\n[\/vc_column_text]<div class=\"divider-wrap\"><div style=\"height: 20px;\" class=\"divider\"><\/div><\/div><div class=\"img-with-aniamtion-wrap \" data-max-width=\"100%\"><div class=\"inner\"><img decoding=\"async\" data-shadow=\"none\" data-shadow-direction=\"middle\" class=\"img-with-animation \" data-delay=\"0\" height=\"80\" width=\"322\" data-animation=\"fade-in\" src=\"https:\/\/leathergoods.es\/wp-content\/uploads\/2017\/08\/iconos-anillas-dia.png\" srcset=\"https:\/\/leathergoods.es\/wp-content\/uploads\/2017\/08\/iconos-anillas-dia.png 322w, https:\/\/leathergoods.es\/wp-content\/uploads\/2017\/08\/iconos-anillas-dia-300x75.png 300w\" sizes=\"100vw\" alt=\"iconos-anillas-dia\" \/><\/div><\/div>[\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; width=&#8221;1\/2&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_gallery type=&#8221;flexslider_style&#8221; images=&#8221;4443,4442,3866,3865,3867&#8243; onclick=&#8221;link_no&#8221; img_size=&#8221;full&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; equal_height=&#8221;yes&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; overlay_strength=&#8221;0.3&#8243;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"divider-wrap\"><div style=\"margin-top: 12px; height: 4px; margin-bottom: 12px;\" data-width=\"100%\" data-animate=\"\" data-animation-delay=\"\" data-color=\"accent-color\" class=\"divider-border\"><\/div><\/div>[\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;40&#8243; bottom_padding=&#8221;40&#8243; overlay_strength=&#8221;0.3&#8243;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;We would like you to provide us with as much information as possible so that we can prepare your personalized 2023 agenda quote with the utmost detail and care.&#8221; font_container=&#8221;tag:h2|text_align:center|color:%23b7a964&#8243; use_theme_fonts=&#8221;yes&#8221;]<div class=\"divider-wrap\"><div style=\"height: 20px;\" class=\"divider\"><\/div><\/div>[vc_raw_html]JTNDYSUyMG5hbWUlM0QlMjJmb3JtdWxhcmlvJTIyJTNFJTNDJTJGYSUzRQ==[\/vc_raw_html][vc_raw_html]JTNDZGl2JTIwY2xhc3MlM0QlMjJfZm9ybV81JTIyJTNFJTNDJTJGZGl2JTNFJTNDc2NyaXB0JTIwc3JjJTNEJTIyaHR0cHMlM0ElMkYlMkZsZWF0aGVyZ29vZHNlcy5hY3RpdmVob3N0ZWQuY29tJTJGZiUyRmVtYmVkLnBocCUzRmlkJTNENSUyMiUyMHR5cGUlM0QlMjJ0ZXh0JTJGamF2YXNjcmlwdCUyMiUyMGNoYXJzZXQlM0QlMjJ1dGYtOCUyMiUzRSUzQyUyRnNjcmlwdCUzRQ==[\/vc_raw_html][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; equal_height=&#8221;yes&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; overlay_strength=&#8221;0.3&#8243;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"divider-wrap\"><div style=\"margin-top: 12px; height: 4px; margin-bottom: 12px;\" data-width=\"100%\" data-animate=\"\" data-animation-delay=\"\" data-color=\"accent-color\" class=\"divider-border\"><\/div><\/div>[\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;40&#8243; overlay_strength=&#8221;0.3&#8243;][vc_column centered_text=&#8221;true&#8221; column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h2 style=\"text-align: center;\"><span style=\"color: #074173;\">Related products<\/span><\/h2>\n[\/vc_column_text]<div class=\"divider-wrap\"><div style=\"margin-top: 10px; width: 40px; height: 3px; margin-bottom: 10px;\" data-width=\"40\" data-animate=\"yes\" data-animation-delay=\"\" data-color=\"extra-color-gradient-2\" class=\"divider-small-border\"><\/div><\/div>[\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; overlay_strength=&#8221;0.3&#8243;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; width=&#8221;1\/3&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"img-with-aniamtion-wrap center\" data-max-width=\"100%\"><div class=\"inner\"><a href=\"\/agenda-semana-vista-wire-o\/\" target=\"_self\" class=\"center\"><img fetchpriority=\"high\" decoding=\"async\" data-shadow=\"none\" data-shadow-direction=\"middle\" class=\"img-with-animation \" data-delay=\"0\" height=\"378\" width=\"600\" data-animation=\"fade-in\" src=\"https:\/\/leathergoods.es\/wp-content\/uploads\/2022\/05\/agenda-2023-semana-vista-wire-o-2.jpg\" srcset=\"https:\/\/leathergoods.es\/wp-content\/uploads\/2022\/05\/agenda-2023-semana-vista-wire-o-2.jpg 600w, https:\/\/leathergoods.es\/wp-content\/uploads\/2022\/05\/agenda-2023-semana-vista-wire-o-2-300x189.jpg 300w\" sizes=\"100vw\" alt=\"\" \/><\/a><\/div><\/div>[vc_column_text]\n<p style=\"text-align: center;\"><strong>Agenda Wire-O week view<\/strong><\/p>\n[\/vc_column_text][vc_column_text]\n<p style=\"text-align: center;\">&#8211;<\/p>\n<p style=\"text-align: center;\">A weekly agenda for carrying documents<\/p>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; width=&#8221;1\/3&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"img-with-aniamtion-wrap center\" data-max-width=\"100%\"><div class=\"inner\"><a href=\"https:\/\/leathergoods.es\/agenda-dia-por-pagina-cosida\/\" target=\"_self\" class=\"center\"><img decoding=\"async\" data-shadow=\"none\" data-shadow-direction=\"middle\" class=\"img-with-animation \" data-delay=\"0\" height=\"600\" width=\"800\" data-animation=\"fade-in\" src=\"https:\/\/leathergoods.es\/wp-content\/uploads\/2022\/06\/agenda-2023-dia-pagina-cosida.jpg\" srcset=\"https:\/\/leathergoods.es\/wp-content\/uploads\/2022\/06\/agenda-2023-dia-pagina-cosida.jpg 800w, https:\/\/leathergoods.es\/wp-content\/uploads\/2022\/06\/agenda-2023-dia-pagina-cosida-300x225.jpg 300w, https:\/\/leathergoods.es\/wp-content\/uploads\/2022\/06\/agenda-2023-dia-pagina-cosida-768x576.jpg 768w\" sizes=\"100vw\" alt=\"\" \/><\/a><\/div><\/div>[vc_column_text]\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p style=\"text-align: center;\"><strong>Agenda Day by Page Stitched<\/strong><\/p>\n<\/div>\n<\/div>\n[\/vc_column_text][vc_column_text]\n<p style=\"text-align: center;\">&#8211;<\/p>\n<p style=\"text-align: center;\">A day-by-page agenda for carrying documents<\/p>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; width=&#8221;1\/3&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"img-with-aniamtion-wrap center\" data-max-width=\"100%\"><div class=\"inner\"><a href=\"https:\/\/flexnotebook.com\/\" target=\"_self\" class=\"center\"><img loading=\"lazy\" decoding=\"async\" data-shadow=\"none\" data-shadow-direction=\"middle\" class=\"img-with-animation \" data-delay=\"0\" height=\"450\" width=\"600\" data-animation=\"fade-in\" src=\"https:\/\/leathergoods.es\/wp-content\/uploads\/2021\/08\/Llaveros-personalizados-llaveros-etiqueta-conjunto.jpg\" srcset=\"https:\/\/leathergoods.es\/wp-content\/uploads\/2021\/08\/Llaveros-personalizados-llaveros-etiqueta-conjunto.jpg 600w, https:\/\/leathergoods.es\/wp-content\/uploads\/2021\/08\/Llaveros-personalizados-llaveros-etiqueta-conjunto-300x225.jpg 300w\" sizes=\"100vw\" alt=\"Llaveros personalizados - llaveros etiqueta conjunto\" \/><\/a><\/div><\/div>[vc_column_text]\n<p style=\"text-align: center;\"><strong>Key chain Label<\/strong><\/p>\n[\/vc_column_text][vc_column_text]\n<p style=\"text-align: center;\">&#8211;<\/p>\n<p style=\"text-align: center;\">Double-sided leather key chain, soft to the touch and with premium finishes. An excellent complement for everyday use.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;50&#8243; bottom_padding=&#8221;15&#8243; overlay_strength=&#8221;0.3&#8243;][vc_column centered_text=&#8221;true&#8221; column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text] &lt;&lt; Return to &#8216;Agendas 2023&#8217; [\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; bg_color=&#8221;#074173&#8243; scene_position=&#8221;center&#8221;&#8230;<\/p>\n","protected":false},"author":13,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-5662","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Personalized day page ring binder agenda | Global Leather Goods<\/title>\n<meta name=\"description\" content=\"Agenda ring binder day page for companies. Personalize your corporate ring binder agenda with the best materials and the most exclusive service.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leathergoods.es\/en\/agenda-ring-binder-day-page\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Personalized day page ring binder agenda | Global Leather Goods\" \/>\n<meta property=\"og:description\" content=\"Agenda ring binder day page for companies. Personalize your corporate ring binder agenda with the best materials and the most exclusive service.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leathergoods.es\/en\/agenda-ring-binder-day-page\/\" \/>\n<meta property=\"og:site_name\" content=\"Global Leather Goods\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Global-Leather-Goods-111025509497046\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-07T10:57:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/leathergoods.es\/en\/agenda-ring-binder-day-page\/\",\"url\":\"https:\/\/leathergoods.es\/en\/agenda-ring-binder-day-page\/\",\"name\":\"Personalized day page ring binder agenda | Global Leather Goods\",\"isPartOf\":{\"@id\":\"https:\/\/leathergoods.es\/en\/#website\"},\"datePublished\":\"2021-09-08T10:37:21+00:00\",\"dateModified\":\"2023-01-07T10:57:45+00:00\",\"description\":\"Agenda ring binder day page for companies. Personalize your corporate ring binder agenda with the best materials and the most exclusive service.\",\"breadcrumb\":{\"@id\":\"https:\/\/leathergoods.es\/en\/agenda-ring-binder-day-page\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/leathergoods.es\/en\/agenda-ring-binder-day-page\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/leathergoods.es\/en\/agenda-ring-binder-day-page\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/leathergoods.es\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Agenda Ring Binder Day page\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/leathergoods.es\/en\/#website\",\"url\":\"https:\/\/leathergoods.es\/en\/\",\"name\":\"Global Leather Goods\",\"description\":\"Fabricante de art\u00edculos de piel &#039;made in Spain&#039;\",\"publisher\":{\"@id\":\"https:\/\/leathergoods.es\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/leathergoods.es\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/leathergoods.es\/en\/#organization\",\"name\":\"Global Leather Goods\",\"url\":\"https:\/\/leathergoods.es\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/leathergoods.es\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/leathergoods.es\/wp-content\/uploads\/2018\/04\/global-leather-goods-logo-web-horizontal.1.png\",\"contentUrl\":\"https:\/\/leathergoods.es\/wp-content\/uploads\/2018\/04\/global-leather-goods-logo-web-horizontal.1.png\",\"width\":807,\"height\":191,\"caption\":\"Global Leather Goods\"},\"image\":{\"@id\":\"https:\/\/leathergoods.es\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Global-Leather-Goods-111025509497046\/\",\"https:\/\/www.instagram.com\/globalleathergoods\/\",\"https:\/\/www.linkedin.com\/company\/global-leather-goods\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Personalized day page ring binder agenda | Global Leather Goods","description":"Agenda ring binder day page for companies. Personalize your corporate ring binder agenda with the best materials and the most exclusive service.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leathergoods.es\/en\/agenda-ring-binder-day-page\/","og_locale":"en_US","og_type":"article","og_title":"Personalized day page ring binder agenda | Global Leather Goods","og_description":"Agenda ring binder day page for companies. Personalize your corporate ring binder agenda with the best materials and the most exclusive service.","og_url":"https:\/\/leathergoods.es\/en\/agenda-ring-binder-day-page\/","og_site_name":"Global Leather Goods","article_publisher":"https:\/\/www.facebook.com\/Global-Leather-Goods-111025509497046\/","article_modified_time":"2023-01-07T10:57:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/leathergoods.es\/en\/agenda-ring-binder-day-page\/","url":"https:\/\/leathergoods.es\/en\/agenda-ring-binder-day-page\/","name":"Personalized day page ring binder agenda | Global Leather Goods","isPartOf":{"@id":"https:\/\/leathergoods.es\/en\/#website"},"datePublished":"2021-09-08T10:37:21+00:00","dateModified":"2023-01-07T10:57:45+00:00","description":"Agenda ring binder day page for companies. Personalize your corporate ring binder agenda with the best materials and the most exclusive service.","breadcrumb":{"@id":"https:\/\/leathergoods.es\/en\/agenda-ring-binder-day-page\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leathergoods.es\/en\/agenda-ring-binder-day-page\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/leathergoods.es\/en\/agenda-ring-binder-day-page\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/leathergoods.es\/en\/"},{"@type":"ListItem","position":2,"name":"Agenda Ring Binder Day page"}]},{"@type":"WebSite","@id":"https:\/\/leathergoods.es\/en\/#website","url":"https:\/\/leathergoods.es\/en\/","name":"Global Leather Goods","description":"Fabricante de art\u00edculos de piel &#039;made in Spain&#039;","publisher":{"@id":"https:\/\/leathergoods.es\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leathergoods.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/leathergoods.es\/en\/#organization","name":"Global Leather Goods","url":"https:\/\/leathergoods.es\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/leathergoods.es\/en\/#\/schema\/logo\/image\/","url":"https:\/\/leathergoods.es\/wp-content\/uploads\/2018\/04\/global-leather-goods-logo-web-horizontal.1.png","contentUrl":"https:\/\/leathergoods.es\/wp-content\/uploads\/2018\/04\/global-leather-goods-logo-web-horizontal.1.png","width":807,"height":191,"caption":"Global Leather Goods"},"image":{"@id":"https:\/\/leathergoods.es\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Global-Leather-Goods-111025509497046\/","https:\/\/www.instagram.com\/globalleathergoods\/","https:\/\/www.linkedin.com\/company\/global-leather-goods\/"]}]}},"_links":{"self":[{"href":"https:\/\/leathergoods.es\/en\/wp-json\/wp\/v2\/pages\/5662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leathergoods.es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/leathergoods.es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/leathergoods.es\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/leathergoods.es\/en\/wp-json\/wp\/v2\/comments?post=5662"}],"version-history":[{"count":1,"href":"https:\/\/leathergoods.es\/en\/wp-json\/wp\/v2\/pages\/5662\/revisions"}],"predecessor-version":[{"id":5663,"href":"https:\/\/leathergoods.es\/en\/wp-json\/wp\/v2\/pages\/5662\/revisions\/5663"}],"wp:attachment":[{"href":"https:\/\/leathergoods.es\/en\/wp-json\/wp\/v2\/media?parent=5662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}